{"id":1375,"date":"2023-03-01T13:32:44","date_gmt":"2023-03-01T05:32:44","guid":{"rendered":"https:\/\/www.hcmedevice.com\/?page_id=1375"},"modified":"2023-05-20T14:38:35","modified_gmt":"2023-05-20T06:38:35","slug":"loopix-wound-drainage-tube-fixing-device","status":"publish","type":"page","link":"https:\/\/www.hcmedevice.com\/de\/loopix-wunddrainageschlauch-befestigungsvorrichtung-2\/","title":{"rendered":"LOOPIX Fixierger\u00e4t f\u00fcr Wunddrainagen"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1375\" class=\"elementor elementor-1375\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c4ec2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c4ec2e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8830041\" data-id=\"8830041\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a77fe1 elementor-widget elementor-widget-elementskit-heading\" data-id=\"1a77fe1\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title\">LOOPIX Fixierger\u00e4t f\u00fcr Wunddrainagen<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Um die Nachteile der traditionellen Nahtmethode bei der chirurgischen Fixierung von Drainagekathetern zu l\u00f6sen.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider elementskit-style-long\"><div class=\"elementskit-border-divider elementskit-style-long\"><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4fa646 elementor-widget elementor-widget-text-editor\" data-id=\"a4fa646\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>LOOPIX ist ein revolution\u00e4res, nicht-invasives Katheterfixierger\u00e4t f\u00fcr den einmaligen Gebrauch zur Sicherung von Wunddrainage-Verweilkathetern im Operationssaal. Anders als bei der herk\u00f6mmlichen Nahtbefestigungsmethode verwenden wir hypoallergenes Haftklebeband und eine patentierte Dual-Locking-Technik, um LOOPIX zu entwickeln \u2013 die durchstichfreie Befestigungsvorrichtung f\u00fcr Drainageschl\u00e4uche.<\/p><p>Das Ger\u00e4t reduziert die Komplikationen einer Infektion und das Risiko einer versehentlichen Extubation. Es spart Zeit und verbessert den Komfort der postoperativen Versorgung. Es f\u00fchrt auch zu weniger Schmerzen und gr\u00f6\u00dferer Patientenzufriedenheit und kommt vielen Patienten zugute, insbesondere denen, die eine Langzeitdrainage ben\u00f6tigen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b37392d\" data-id=\"b37392d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2983b5c elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"2983b5c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-drainage-catheter-stabilization-device-and-Gauze-CE.jpg\" class=\"elementor-animation-float attachment-large size-large wp-image-153\" alt=\"LOOPIX Fixierger\u00e4t f\u00fcr Wunddrainagen\" srcset=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-drainage-catheter-stabilization-device-and-Gauze-CE.jpg 600w, https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-drainage-catheter-stabilization-device-and-Gauze-CE-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-080e085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"080e085\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef0714a\" data-id=\"ef0714a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68fe2ca elementor-mobile-align-center elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"68fe2ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjE1NjYiLCJ0b2dnbGUiOmZhbHNlfQ==\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REQUEST QUOTE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fbaeb8 elementor-mobile-align-center elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"7fbaeb8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2023\/01\/Brochure-LOOPIX-Wound-Drainage-Tube-Fixing-Device.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Brosch\u00fcre - LOOPIX Fixierger\u00e4t f\u00fcr Wunddrainagen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ef2532 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ef2532\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8d1c2b\" data-id=\"e8d1c2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be384a1 elementor-widget elementor-widget-video\" data-id=\"be384a1\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/ajQQNpzTdzE&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2703b59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2703b59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7dbd42e\" data-id=\"7dbd42e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22c06ef elementor-widget elementor-widget-heading\" data-id=\"22c06ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjEzODEiLCJ0b2dnbGUiOmZhbHNlfQ==\">Product Benefits<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-580d440\" data-id=\"580d440\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d259595 elementor-widget elementor-widget-heading\" data-id=\"d259595\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjE0NzUiLCJ0b2dnbGUiOmZhbHNlfQ==\">Comparison of LOOPIX and Suture<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7158135 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7158135\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d435956\" data-id=\"d435956\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c5de39 elementor-widget elementor-widget-heading\" data-id=\"6c5de39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjEzODkiLCJ0b2dnbGUiOmZhbHNlfQ==\">Patentierte Struktur<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d037d2\" data-id=\"2d037d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98bf2fc elementor-widget elementor-widget-heading\" data-id=\"98bf2fc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjEzODYiLCJ0b2dnbGUiOmZhbHNlfQ==\">Klinische Anwendung<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54e46c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54e46c6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7f3ad8\" data-id=\"a7f3ad8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d94f54 elementor-widget elementor-widget-heading\" data-id=\"5d94f54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action:action=popup:open&settings=eyJpZCI6IjEzOTIiLCJ0b2dnbGUiOmZhbHNlfQ==\">Spezifikation<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58d154b\" data-id=\"58d154b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ca6c22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ca6c22\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36a15c8\" data-id=\"36a15c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06f45c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06f45c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e72fb7a\" data-id=\"e72fb7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b349d9 elementor-widget elementor-widget-heading\" data-id=\"2b349d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Learn more about the LOOPIX clinical cases:<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7024397\" data-id=\"7024397\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4b163f elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"a4b163f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hcmedevice.com\/de\/loopix-klinische-falle\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Typische klinische F\u00e4lle<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e94f3a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e94f3a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7534e87\" data-id=\"7534e87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8de8962 elementor-widget elementor-widget-heading\" data-id=\"8de8962\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Learn how to use LOOPIX wound drainage tube fixing device\uff1a<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f0cd0a1\" data-id=\"f0cd0a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d22a6a elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2d22a6a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hcmedevice.com\/de\/gebrauchsanweisung-loopix-wunddrainageschlauch-befestigungsvorrichtung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">So verwenden Sie LOOPIX<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-181e098 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"181e098\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ff05579\" data-id=\"ff05579\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-001745c elementor-widget elementor-widget-heading\" data-id=\"001745c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zertifikat<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-03547bf\" data-id=\"03547bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8e46b5 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"a8e46b5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/CE-LOOPIX-Drainage-Tube-Securement-Device.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download: CE-Zertifikat<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7eac5da\" data-id=\"7eac5da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a472bf elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2a472bf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/ISO13485-LOOPIX-Drainage-Tube-Securement-Device.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download: ISO13485-Zertifikat<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-225d086 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"225d086\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4cae1f\" data-id=\"e4cae1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0ac411 elementor-widget elementor-widget-heading\" data-id=\"d0ac411\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verteilung<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d737a34 elementor-widget elementor-widget-text-editor\" data-id=\"d737a34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Wir suchen Partner als unsere autorisierten Distributoren auf den globalen M\u00e4rkten. Wir sch\u00e4tzen jeden Partner, egal ob vorhanden oder potenziell, und sind bereit, gemeinsam zu wachsen.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79f5e8f elementor-widget elementor-widget-heading\" data-id=\"79f5e8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">M\u00f6chten Sie unser Vertriebspartner werden? Kontaktieren Sie uns, um die Details zu erfahren.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b2a4f2 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3b2a4f2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hcmedevice.com\/de\/kontaktiere-uns\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns f\u00fcr Einzelheiten<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-70e2786\" data-id=\"70e2786\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff729d6 elementor-widget elementor-widget-image\" data-id=\"ff729d6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"844\" height=\"461\" src=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/World-map.png\" class=\"attachment-large size-large wp-image-99\" alt=\"\" srcset=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/World-map.png 844w, https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/World-map-300x164.png 300w, https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/World-map-768x419.png 768w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>LOOPIX Wound Drainage Tube Fixing Device To solve the disadvantages of the traditional suturing method in surgical drainage catheter fixation. LOOPIX is a revolutionary single-use non-invasive catheter fixation device for securing wound drainage indwelling catheters in the operating room. Different from the traditional suturing securing method, we use hypoallergenic pressure-sensitive adhesive tape and a patented [&hellip;]<\/p>","protected":false},"author":1,"featured_media":96,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1375","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LOOPIX Wound Drainage Tube Fixing Device - Haichuang Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hcmedevice.com\/de\/loopix-wunddrainageschlauch-befestigungsvorrichtung-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOOPIX Wound Drainage Tube Fixing Device - Haichuang Medical\" \/>\n<meta property=\"og:description\" content=\"LOOPIX Wound Drainage Tube Fixing Device To solve the disadvantages of the traditional suturing method in surgical drainage catheter fixation. LOOPIX is a revolutionary single-use non-invasive catheter fixation device for securing wound drainage indwelling catheters in the operating room. Different from the traditional suturing securing method, we use hypoallergenic pressure-sensitive adhesive tape and a patented [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hcmedevice.com\/de\/loopix-wunddrainageschlauch-befestigungsvorrichtung-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Haichuang Medical\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-20T06:38:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-device-and-gauze.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/\",\"url\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/\",\"name\":\"LOOPIX Wound Drainage Tube Fixing Device - Haichuang Medical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hcmedevice.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Loopix-device-and-gauze.jpg\",\"datePublished\":\"2023-03-01T05:32:44+00:00\",\"dateModified\":\"2023-05-20T06:38:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hcmedevice.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Loopix-device-and-gauze.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hcmedevice.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Loopix-device-and-gauze.jpg\",\"width\":720,\"height\":720,\"caption\":\"LOOPIX WOUND DRAINAGE TUBE FIXING DEVICE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/loopix-wound-drainage-tube-fixing-device\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hcmedevice.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LOOPIX Wound Drainage Tube Fixing Device\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hcmedevice.com\\\/\",\"name\":\"Haichuang Medical\",\"description\":\"Innovation Defines Life\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hcmedevice.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/#organization\",\"name\":\"Haichuang Medical\",\"url\":\"https:\\\/\\\/www.hcmedevice.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hcmedevice.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Haichuang-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.hcmedevice.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Haichuang-Logo.png\",\"width\":800,\"height\":164,\"caption\":\"Haichuang Medical\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hcmedevice.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOOPIX Wound Drainage Tube Fixing Device - Haichuang Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hcmedevice.com\/de\/loopix-wunddrainageschlauch-befestigungsvorrichtung-2\/","og_locale":"de_DE","og_type":"article","og_title":"LOOPIX Wound Drainage Tube Fixing Device - Haichuang Medical","og_description":"LOOPIX Wound Drainage Tube Fixing Device To solve the disadvantages of the traditional suturing method in surgical drainage catheter fixation. LOOPIX is a revolutionary single-use non-invasive catheter fixation device for securing wound drainage indwelling catheters in the operating room. Different from the traditional suturing securing method, we use hypoallergenic pressure-sensitive adhesive tape and a patented [&hellip;]","og_url":"https:\/\/www.hcmedevice.com\/de\/loopix-wunddrainageschlauch-befestigungsvorrichtung-2\/","og_site_name":"Haichuang Medical","article_modified_time":"2023-05-20T06:38:35+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-device-and-gauze.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/","url":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/","name":"LOOPIX Wound Drainage Tube Fixing Device - Haichuang Medical","isPartOf":{"@id":"https:\/\/www.hcmedevice.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/#primaryimage"},"image":{"@id":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-device-and-gauze.jpg","datePublished":"2023-03-01T05:32:44+00:00","dateModified":"2023-05-20T06:38:35+00:00","breadcrumb":{"@id":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/#primaryimage","url":"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-device-and-gauze.jpg","contentUrl":"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2022\/12\/Loopix-device-and-gauze.jpg","width":720,"height":720,"caption":"LOOPIX WOUND DRAINAGE TUBE FIXING DEVICE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hcmedevice.com\/loopix-wound-drainage-tube-fixing-device\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hcmedevice.com\/"},{"@type":"ListItem","position":2,"name":"LOOPIX Wound Drainage Tube Fixing Device"}]},{"@type":"WebSite","@id":"https:\/\/www.hcmedevice.com\/#website","url":"https:\/\/www.hcmedevice.com\/","name":"Haichuang Medical","description":"Innovation Defines Life","publisher":{"@id":"https:\/\/www.hcmedevice.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hcmedevice.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.hcmedevice.com\/#organization","name":"Haichuang Medical","url":"https:\/\/www.hcmedevice.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hcmedevice.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2024\/10\/Haichuang-Logo.png","contentUrl":"https:\/\/www.hcmedevice.com\/wp-content\/uploads\/2024\/10\/Haichuang-Logo.png","width":800,"height":164,"caption":"Haichuang Medical"},"image":{"@id":"https:\/\/www.hcmedevice.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/pages\/1375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/comments?post=1375"}],"version-history":[{"count":15,"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/pages\/1375\/revisions"}],"predecessor-version":[{"id":1658,"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/pages\/1375\/revisions\/1658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/media\/96"}],"wp:attachment":[{"href":"https:\/\/www.hcmedevice.com\/de\/wp-json\/wp\/v2\/media?parent=1375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}